{"id":13315,"date":"2024-03-14T10:59:10","date_gmt":"2024-03-14T09:59:10","guid":{"rendered":"https:\/\/infn.sitebysite.it\/physics\/physics-of-the-universe\/il-big-bang-e-luniverso\/"},"modified":"2024-12-27T15:42:55","modified_gmt":"2024-12-27T14:42:55","slug":"the-big-bang-and-the-universe","status":"publish","type":"page","link":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/","title":{"rendered":"The Big Bang and the universe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Big Bang theory is currently the most reliable scientific theory about the origins of the cosmos. It postulates that our universe started approximately 13.8 billion years ago from an extremely hot and dense state and, since then, has expanded basically continuously.<\/p>\n","protected":false},"author":19,"featured_media":14311,"parent":12394,"menu_order":158,"comment_status":"closed","ping_status":"closed","template":"pages\/page-block-template.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-13315","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare<\/title>\n<meta name=\"description\" content=\"Scopri la teoria del Big Bang con l&#039;INFN: dall&#039;origine dell&#039;universo circa 13,8 miliardi di anni fa all&#039;espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare\" \/>\n<meta property=\"og:description\" content=\"Scopri la teoria del Big Bang con l&#039;INFN: dall&#039;origine dell&#039;universo circa 13,8 miliardi di anni fa all&#039;espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Nazionale di Fisica Nucleare\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-27T14:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/\",\"url\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/\",\"name\":\"The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare\",\"isPartOf\":{\"@id\":\"https:\/\/infn.sitebysite.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg\",\"datePublished\":\"2024-03-14T09:59:10+00:00\",\"dateModified\":\"2024-12-27T14:42:55+00:00\",\"description\":\"Scopri la teoria del Big Bang con l'INFN: dall'origine dell'universo circa 13,8 miliardi di anni fa all'espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse\",\"breadcrumb\":{\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage\",\"url\":\"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg\",\"contentUrl\":\"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg\",\"width\":1400,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/infn.sitebysite.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Physics\",\"item\":\"https:\/\/infn.sitebysite.it\/en\/physics\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Physics of the universe\",\"item\":\"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"The Big Bang and the universe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/infn.sitebysite.it\/en\/#website\",\"url\":\"https:\/\/infn.sitebysite.it\/en\/\",\"name\":\"Istituto Nazionale di Fisica Nucleare\",\"description\":\"\",\"alternateName\":\"Istituto Nazionale di Fisica Nucleare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/infn.sitebysite.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare","description":"Scopri la teoria del Big Bang con l'INFN: dall'origine dell'universo circa 13,8 miliardi di anni fa all'espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare","og_description":"Scopri la teoria del Big Bang con l'INFN: dall'origine dell'universo circa 13,8 miliardi di anni fa all'espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse","og_url":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/","og_site_name":"Istituto Nazionale di Fisica Nucleare","article_modified_time":"2024-12-27T14:42:55+00:00","og_image":[{"width":1400,"height":1000,"url":"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/","url":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/","name":"The Big Bang and the universe - Istituto Nazionale di Fisica Nucleare","isPartOf":{"@id":"https:\/\/infn.sitebysite.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage"},"image":{"@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage"},"thumbnailUrl":"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg","datePublished":"2024-03-14T09:59:10+00:00","dateModified":"2024-12-27T14:42:55+00:00","description":"Scopri la teoria del Big Bang con l'INFN: dall'origine dell'universo circa 13,8 miliardi di anni fa all'espansione cosmica continua. Approfondisci le prove sperimentali, come la radiazione cosmica di fondo e le osservazioni di Hubble, e le fasi evolutive che hanno portato alla formazione di stelle, galassie e strutture complesse","breadcrumb":{"@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#primaryimage","url":"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg","contentUrl":"https:\/\/infn.sitebysite.it\/wp-content\/uploads\/2024\/07\/bigbangeuniverso1.jpg","width":1400,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/the-big-bang-and-the-universe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infn.sitebysite.it\/en\/"},{"@type":"ListItem","position":2,"name":"Physics","item":"https:\/\/infn.sitebysite.it\/en\/physics\/"},{"@type":"ListItem","position":3,"name":"Physics of the universe","item":"https:\/\/infn.sitebysite.it\/en\/physics\/physics-of-the-universe\/"},{"@type":"ListItem","position":4,"name":"The Big Bang and the universe"}]},{"@type":"WebSite","@id":"https:\/\/infn.sitebysite.it\/en\/#website","url":"https:\/\/infn.sitebysite.it\/en\/","name":"Istituto Nazionale di Fisica Nucleare","description":"","alternateName":"Istituto Nazionale di Fisica Nucleare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infn.sitebysite.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:30:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/pages\/13315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/comments?post=13315"}],"version-history":[{"count":18,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/pages\/13315\/revisions"}],"predecessor-version":[{"id":23095,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/pages\/13315\/revisions\/23095"}],"up":[{"embeddable":true,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/pages\/12394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/media\/14311"}],"wp:attachment":[{"href":"https:\/\/infn.sitebysite.it\/en\/wp-json\/wp\/v2\/media?parent=13315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}